{"id":1963,"date":"2021-09-01T14:37:35","date_gmt":"2021-09-01T12:37:35","guid":{"rendered":"https:\/\/aeropolis.site\/boletin\/?p=1963"},"modified":"2022-09-05T13:56:38","modified_gmt":"2022-09-05T11:56:38","slug":"la-republica-de-kazajistan-encarga-dos-airbus-a400m","status":"publish","type":"post","link":"https:\/\/www.aeropolis.es\/boletin\/la-republica-de-kazajistan-encarga-dos-airbus-a400m\/","title":{"rendered":"La Rep\u00fablica de Kazajist\u00e1n encarga dos Airbus A400M"},"content":{"rendered":"<h3 class=\"fusion-responsive-typography-calculated\" data-fontsize=\"18\" data-lineheight=\"22.5px\">La primera entrega est\u00e1 prevista para 2024<\/h3>\n<p>La Rep\u00fablica de Kazajist\u00e1n ha formalizado un pedido de dos aviones Airbus A400M y se convierte en el noveno operador de esta aeronave, sum\u00e1ndose a Alemania, Francia, Reino Unido, Espa\u00f1a, Turqu\u00eda, B\u00e9lgica, Malasia y Luxemburgo.<\/p>\n<p>La entrega del primer avi\u00f3n est\u00e1 prevista para 2024 y el acuerdo incluye tambi\u00e9n un completo paquete de mantenimiento y formaci\u00f3n. Junto al contrato se ha firmado tambi\u00e9n un memorando de entendimiento que prev\u00e9 la colaboraci\u00f3n en servicios de mantenimiento y reparaci\u00f3n (MRO). Su primera medida consistir\u00e1 en la creaci\u00f3n de un centro local de mantenimiento para el C295.<\/p>\n<p>\u201cEl A400M se convertir\u00e1 en la piedra angular de las operaciones de transporte a\u00e9reo t\u00e1ctico y estrat\u00e9gico de Kazajist\u00e1n\u201d, afirm\u00f3 Michael Schoellhorn, CEO de Airbus Defence and Space. \u201cEste nuevo contrato de exportaci\u00f3n eleva el n\u00famero total de pedidos del A400M a 176 aviones, una cifra que esperamos incrementar en un futuro pr\u00f3ximo. Con m\u00e1s de cien aviones entregados y cien mil horas de vuelo operativo, el A400M ha demostrado sus capacidades y ha alcanzado el estado de madurez que muchos clientes potenciales estaban esperando\u201d.<\/p>\n<p>Con la capacidad de adaptarse en el conjunto de equipos del pa\u00eds, desempe\u00f1ando misiones militares, civiles y humanitarias, el A400M permitir\u00e1 a Kazajistan responder con rapidez a cualquier crisis desplegando capacidades decisivas a larga distancia y facilitando un acceso eficaz a zonas remotas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La primera entrega est\u00e1 prevista para 2024 La Rep\u00fablica de Kazajist\u00e1n ha formalizado un pedido de dos aviones Airbus A400M y se convierte en el noveno operador de esta aeronave, sum\u00e1ndose a Alemania, Francia, Reino Unido, Espa\u00f1a, Turqu\u00eda, B\u00e9lgica, Malasia y Luxemburgo. La entrega del primer avi\u00f3n est\u00e1 prevista para 2024 y el acuerdo incluye tambi\u00e9n un completo paquete de <a href=\"https:\/\/www.aeropolis.es\/boletin\/la-republica-de-kazajistan-encarga-dos-airbus-a400m\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":1964,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[11],"class_list":["post-1963","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nuestras-empresas","tag-airbus"],"_links":{"self":[{"href":"https:\/\/www.aeropolis.es\/boletin\/wp-json\/wp\/v2\/posts\/1963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aeropolis.es\/boletin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aeropolis.es\/boletin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aeropolis.es\/boletin\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aeropolis.es\/boletin\/wp-json\/wp\/v2\/comments?post=1963"}],"version-history":[{"count":1,"href":"https:\/\/www.aeropolis.es\/boletin\/wp-json\/wp\/v2\/posts\/1963\/revisions"}],"predecessor-version":[{"id":1965,"href":"https:\/\/www.aeropolis.es\/boletin\/wp-json\/wp\/v2\/posts\/1963\/revisions\/1965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aeropolis.es\/boletin\/wp-json\/wp\/v2\/media\/1964"}],"wp:attachment":[{"href":"https:\/\/www.aeropolis.es\/boletin\/wp-json\/wp\/v2\/media?parent=1963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aeropolis.es\/boletin\/wp-json\/wp\/v2\/categories?post=1963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aeropolis.es\/boletin\/wp-json\/wp\/v2\/tags?post=1963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}