{"id":1676,"date":"2021-07-14T09:26:02","date_gmt":"2021-07-14T09:26:02","guid":{"rendered":"http:\/\/boletin.aeropolis.es\/boletin\/?p=1676"},"modified":"2021-10-18T18:28:47","modified_gmt":"2021-10-18T16:28:47","slug":"airbus-entrega-el-c295-numero-200","status":"publish","type":"post","link":"https:\/\/www.aeropolis.es\/boletin\/airbus-entrega-el-c295-numero-200\/","title":{"rendered":"Airbus entrega el C295 n\u00famero 200"},"content":{"rendered":"<h3>La flota mundial del avi\u00f3n alcanza este hito con una nueva entrega a la Real Fuerza A\u00e9rea Canadiense<\/h3>\n<p>Airbus Defence and Space realiz\u00f3 la entrega del avi\u00f3n al cliente en su l\u00ednea de montaje de Medium and Light Aircraft de San Pablo, Sevilla. En los pr\u00f3ximos d\u00edas, la aeronave completar\u00e1 su vuelo ferry hasta el Ala 19 de la Base de las Fuerzas Canadienses de Comox, en la Columbia Brit\u00e1nica, Canad\u00e1, donde tendr\u00e1 su base. La compa\u00f1\u00eda ha entregado formalmente siete C295 de un total de 16 unidades previstas para el programa Fixed-Wing Search and Rescue (FWSAR).<\/p>\n<p>Este nuevo avi\u00f3n FWSAR se convierte en la unidad n\u00famero 200 de la comunidad del C295. El avi\u00f3n t\u00e1ctico de Airbus, altamente vers\u00e1til y eficiente, ha recibido pedidos de 34 operadores militares y civiles de todo el mundo, desde Canad\u00e1 y Egipto hasta Espa\u00f1a e Indonesia.<\/p>\n<h2>Ceremonia en San Pablo<\/h2>\n<p>Junto al Presidente de Airbus Espa\u00f1a Alberto Guti\u00e9rrez, asistieron al acto de entrega Juan Manuel Moreno Bonilla, presidente de la Junta de Andaluc\u00eda, y el agregado militar de la Embajada de Canad\u00e1. Tambi\u00e9n participaron en la ceremonia otros altos cargos de Airbus como Francisco S\u00e1nchez Segura, Head of Engineering de Defence and Space, y Felipe Steinmetz, Head of Light &amp; Medium Aircraft.<\/p>\n<p>\u201cLa planta de San Pablo es un referente en Europa, una de las pocas plantas que albergan una l\u00ednea de montaje final de aviones. Aqu\u00ed se hace el montaje final de los A400M y C295, dos aviones que reflejan el esp\u00edritu de innovaci\u00f3n y alta tecnolog\u00eda de Airbus. Mi m\u00e1s sincera enhorabuena a todos los equipos de la compa\u00f1\u00eda que participan en este programa y que han hecho del C295 el l\u00edder mundial en el segmento del transporte t\u00e1ctico militar. El \u00e9xito de alcanzar las 200 entregas os pertenece por completo\u00bb, subray\u00f3 Alberto Guti\u00e9rrez.<\/p>\n<p>\u201cEl C295 representa la cultura del esfuerzo. Es fruto del trabajo, del saber hacer y de la experiencia acumulada de cientos de compa\u00f1eros en Airbus que trabajamos cada d\u00eda por y para la excelencia industrial y, por supuesto, para la satisfacci\u00f3n de las necesidades de nuestros clientes\u201d, a\u00f1adi\u00f3 Iv\u00e1n Mart\u00ednez, Head of FAL &amp; MRO, Medium and Light Programme, Airbus Defence and Space.<\/p>\n<p>Por su parte, el presidente andaluz Juan Manuel Moreno quiso destacar al sector aeroespacial y de defensa como \u201cclave en la econom\u00eda y estrat\u00e9gico para el progreso de Andaluc\u00eda\u201d al ocupar los primeros puestos en exportaciones y contribuir con un porcentaje creciente al PIB de la regi\u00f3n.<\/p>\n<div class=\"fusion-slider-sc fusion-flexslider-loading flexslider flexslider-hover-type-none\" data-slideshow_autoplay=\"1\" data-slideshow_smooth_height=\"0\" data-slideshow_speed=\"7000\" style=\"max-width:100%;height:100%;\"><ul class=\"slides\"><li class=\"image\"><span class=\"fusion-image-hover-element hover-type-none\"><img decoding=\"async\" src=\"https:\/\/www.aeropolis.es\/boletin\/wp-content\/uploads\/2021\/07\/51302751640_188f66e610_o-e1626253370941.jpg\" width=\"1024\" height=\"576\" class=\"wp-image-1682\" srcset=\"https:\/\/www.aeropolis.es\/boletin\/wp-content\/uploads\/sites\/2\/2021\/07\/51302751640_188f66e610_o-e1626253370941-200x113.jpg 200w, https:\/\/www.aeropolis.es\/boletin\/wp-content\/uploads\/sites\/2\/2021\/07\/51302751640_188f66e610_o-e1626253370941-400x225.jpg 400w, https:\/\/www.aeropolis.es\/boletin\/wp-content\/uploads\/sites\/2\/2021\/07\/51302751640_188f66e610_o-e1626253370941-600x338.jpg 600w, https:\/\/www.aeropolis.es\/boletin\/wp-content\/uploads\/sites\/2\/2021\/07\/51302751640_188f66e610_o-e1626253370941-800x450.jpg 800w, https:\/\/www.aeropolis.es\/boletin\/wp-content\/uploads\/sites\/2\/2021\/07\/51302751640_188f66e610_o-e1626253370941.jpg 1024w\" sizes=\"(max-width: 800px) 100vw, 1024px\" \/><\/span><\/li><li class=\"image\"><span class=\"fusion-image-hover-element hover-type-none\"><img decoding=\"async\" src=\"https:\/\/www.aeropolis.es\/boletin\/wp-content\/uploads\/2021\/07\/5-e1626253523330.jpg\" width=\"640\" height=\"360\" class=\"wp-image-1680\" srcset=\"https:\/\/www.aeropolis.es\/boletin\/wp-content\/uploads\/sites\/2\/2021\/07\/5-e1626253523330-200x113.jpg 200w, https:\/\/www.aeropolis.es\/boletin\/wp-content\/uploads\/sites\/2\/2021\/07\/5-e1626253523330-400x225.jpg 400w, https:\/\/www.aeropolis.es\/boletin\/wp-content\/uploads\/sites\/2\/2021\/07\/5-e1626253523330-600x338.jpg 600w, https:\/\/www.aeropolis.es\/boletin\/wp-content\/uploads\/sites\/2\/2021\/07\/5-e1626253523330.jpg 640w\" sizes=\"(max-width: 800px) 100vw, 640px\" \/><\/span><\/li><li class=\"image\"><span class=\"fusion-image-hover-element hover-type-none\"><img decoding=\"async\" src=\"https:\/\/www.aeropolis.es\/boletin\/wp-content\/uploads\/2021\/07\/4-e1626253561158.jpg\" width=\"640\" height=\"360\" class=\"wp-image-1679\" srcset=\"https:\/\/www.aeropolis.es\/boletin\/wp-content\/uploads\/sites\/2\/2021\/07\/4-e1626253561158-200x113.jpg 200w, https:\/\/www.aeropolis.es\/boletin\/wp-content\/uploads\/sites\/2\/2021\/07\/4-e1626253561158-400x225.jpg 400w, https:\/\/www.aeropolis.es\/boletin\/wp-content\/uploads\/sites\/2\/2021\/07\/4-e1626253561158-600x338.jpg 600w, https:\/\/www.aeropolis.es\/boletin\/wp-content\/uploads\/sites\/2\/2021\/07\/4-e1626253561158.jpg 640w\" sizes=\"(max-width: 800px) 100vw, 640px\" \/><\/span><\/li><li class=\"image\"><span class=\"fusion-image-hover-element hover-type-none\"><img decoding=\"async\" src=\"https:\/\/www.aeropolis.es\/boletin\/wp-content\/uploads\/2021\/07\/1-e1626253605457.jpg\" width=\"640\" height=\"360\" class=\"wp-image-1678\" srcset=\"https:\/\/www.aeropolis.es\/boletin\/wp-content\/uploads\/sites\/2\/2021\/07\/1-e1626253605457-200x113.jpg 200w, https:\/\/www.aeropolis.es\/boletin\/wp-content\/uploads\/sites\/2\/2021\/07\/1-e1626253605457-400x225.jpg 400w, https:\/\/www.aeropolis.es\/boletin\/wp-content\/uploads\/sites\/2\/2021\/07\/1-e1626253605457-600x338.jpg 600w, https:\/\/www.aeropolis.es\/boletin\/wp-content\/uploads\/sites\/2\/2021\/07\/1-e1626253605457.jpg 640w\" sizes=\"(max-width: 800px) 100vw, 640px\" \/><\/span><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La flota mundial del avi\u00f3n alcanza este hito con una nueva entrega a la Real Fuerza A\u00e9rea Canadiense Airbus Defence and Space realiz\u00f3 la entrega del avi\u00f3n al cliente en su l\u00ednea de montaje de Medium and Light Aircraft de San Pablo, Sevilla. En los pr\u00f3ximos d\u00edas, la aeronave completar\u00e1 su vuelo ferry hasta el Ala 19 de la Base <a href=\"https:\/\/www.aeropolis.es\/boletin\/airbus-entrega-el-c295-numero-200\/\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":1659,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[11],"class_list":["post-1676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nuestras-empresas","tag-airbus"],"_links":{"self":[{"href":"https:\/\/www.aeropolis.es\/boletin\/wp-json\/wp\/v2\/posts\/1676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aeropolis.es\/boletin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aeropolis.es\/boletin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aeropolis.es\/boletin\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aeropolis.es\/boletin\/wp-json\/wp\/v2\/comments?post=1676"}],"version-history":[{"count":1,"href":"https:\/\/www.aeropolis.es\/boletin\/wp-json\/wp\/v2\/posts\/1676\/revisions"}],"predecessor-version":[{"id":1907,"href":"https:\/\/www.aeropolis.es\/boletin\/wp-json\/wp\/v2\/posts\/1676\/revisions\/1907"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aeropolis.es\/boletin\/wp-json\/wp\/v2\/media\/1659"}],"wp:attachment":[{"href":"https:\/\/www.aeropolis.es\/boletin\/wp-json\/wp\/v2\/media?parent=1676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aeropolis.es\/boletin\/wp-json\/wp\/v2\/categories?post=1676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aeropolis.es\/boletin\/wp-json\/wp\/v2\/tags?post=1676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}